{"id":1952,"date":"2021-06-15T05:56:58","date_gmt":"2021-06-15T05:56:58","guid":{"rendered":"https:\/\/borealisclima.com\/?p=1952"},"modified":"2025-06-26T11:53:30","modified_gmt":"2025-06-26T10:53:30","slug":"afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs","status":"publish","type":"post","link":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/","title":{"rendered":"L&rsquo;AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs."},"content":{"rendered":"<p><a href=\"https:\/\/www.afec.es\"><span style=\"font-weight: 400;\">AFEC<\/span><\/a><span style=\"font-weight: 400;\">, l\u2019Association des Fabricants d\u2019\u00c9quipements de Climatisation, a publi\u00e9 le guide des \u00ab\u00a0Recommandations de Ventilation pour les \u00c9tablissements Scolaires\u00a0\u00bb, auquel <a href=\"https:\/\/borealisclima.com\" target=\"_blank\" rel=\"noopener noreferrer\">Borealis<\/a> a collabor\u00e9 en tant que membre du groupe de travail charg\u00e9 de son \u00e9laboration.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ce guide propose diff\u00e9rentes recommandations,<\/span><b> destin\u00e9es aux dirigeants d\u2019\u00e9tablissements, aux enseignants, aux associations de parents, aux administrations publiques, ainsi qu\u2019aux gestionnaires d\u2019\u00e9tablissements scolaires<\/b><span style=\"font-weight: 400;\">, dans le but d\u2019aider \u00e0 choisir les meilleures techniques disponibles permettant une ventilation ad\u00e9quate des salles de classe et autres espaces, garantissant ainsi une activit\u00e9 \u00e9ducative saine, s\u00fbre et efficace.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le document traite de divers sujets tels que : les avantages de la ventilation ; les conditions int\u00e9rieures de temp\u00e9rature, d&rsquo;humidit\u00e9 et de ventilation ; la ventilation naturelle et m\u00e9canique ; la purification par diff\u00e9rentes technologies ; le contr\u00f4le de l&rsquo;humidit\u00e9 ; l\u2019entretien, etc.<\/span><\/p>\n<p><b>Consulter le document<\/b><span style=\"font-weight: 400;\"> : <a href=\"https:\/\/www.afec.es\/documentos\/recomendaciones-centros-educativos-junio-2021.pdf\">https:\/\/www.afec.es\/documentos\/recomendaciones-centros-educativos-junio-2021.pdf<\/a><\/span><\/p>\n<h2><b>Recommandations de ventilation pour les \u00e9tablissements scolaires<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Une ventilation ad\u00e9quate dans les \u00e9tablissements scolaires contribue \u00e0 am\u00e9liorer la performance scolaire, \u00e0 cr\u00e9er des espaces plus sains et confortables, ainsi qu&rsquo;\u00e0 r\u00e9duire le risque de transmission des maladies.<\/span><\/p>\n<p><a href=\"https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/02\/imagen-borealis-FR.webp\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4682 aligncenter\" src=\"https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/02\/imagen-borealis-FR-300x196.webp\" alt=\"\" width=\"895\" height=\"585\" srcset=\"https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/02\/imagen-borealis-FR-300x196.webp 300w, https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/02\/imagen-borealis-FR-1024x671.webp 1024w, https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/02\/imagen-borealis-FR-768x503.webp 768w, https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/02\/imagen-borealis-FR-450x295.webp 450w, https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2025\/02\/imagen-borealis-FR.webp 1165w\" sizes=\"auto, (max-width: 895px) 100vw, 895px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Ce document a \u00e9t\u00e9 \u00e9labor\u00e9 par des experts techniques sp\u00e9cialis\u00e9s dans le domaine, parmi lesquels Borealis, qui fait partie de l\u2019AFEC. Il est important de souligner que les solutions techniques finalement adopt\u00e9es dans chaque \u00e9tablissement <strong>doivent \u00eatre v\u00e9rifi\u00e9es et mises en \u0153uvre avec un accompagnement technique professionnel<\/strong>. La meilleure solution est d\u2019installer un syst\u00e8me de ventilation m\u00e9canique adapt\u00e9 aux salles de classe et aux espaces \u00e9ducatifs. Toute mesure visant \u00e0 am\u00e9liorer la ventilation, la purification ou la r\u00e9duction de l\u2019occupation des locaux constitue une avanc\u00e9e par rapport \u00e0 la pire situation possible, qui est un espace d\u00e9pourvu de ventilation et de renouvellement d\u2019air ad\u00e9quats.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un point important \u00e0 noter est que, depuis l&rsquo;application du <strong>R\u00e8glement des Installations Thermiques dans les B\u00e2timents (RITE)<\/strong>, publi\u00e9 en 2007, la r\u00e9glementation exige que les nouveaux b\u00e2timents non r\u00e9sidentiels soient \u00e9quip\u00e9s de syst\u00e8mes de ventilation m\u00e9canique. Cependant, une grande partie des b\u00e2timents \u00e9ducatifs ont \u00e9t\u00e9 construits avant cette date et peuvent ne pas disposer de syst\u00e8mes de ventilation m\u00e9canique, fonctionnant uniquement avec une ventilation naturelle, laquelle peut parfois \u00eatre inefficace en raison de conditions m\u00e9t\u00e9orologiques, du bruit, de la pollution, etc.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">C\u2019est pourquoi ce guide propose des recommandations valables aussi bien pour les b\u00e2timents relevant du RITE en vigueur que pour ceux construits avant 2007.<\/span><\/p>\n<h2><b>Avantages de la ventilation<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Il est prouv\u00e9 qu\u2019une <strong>ventilation<\/strong> ad\u00e9quate permet de :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Am\u00e9liorer la performance scolaire.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Cr\u00e9er des espaces plus sains et confortables.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">R\u00e9duire le risque de transmission des maladies en cas de pr\u00e9sence d\u2019une personne infectieuse dans un espace clos.<\/span><\/li>\n<\/ul>\n<h2><b>Conditions int\u00e9rieures de temp\u00e9rature, d&rsquo;humidit\u00e9 et de ventilation<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Les conditions de temp\u00e9rature et d\u2019humidit\u00e9 dans les salles de classe doivent \u00eatre maintenues autant que possible dans les plages recommand\u00e9es :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">La temp\u00e9rature doit \u00eatre comprise entre 21\u00baC et 23\u00baC en hiver, et entre 24\u00baC et 26\u00baC en \u00e9t\u00e9.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">L\u2019humidit\u00e9 relative doit \u00eatre maintenue entre 40 % et 60 %.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Le respect de ces valeurs optimise la sant\u00e9 et r\u00e9duit la prolif\u00e9ration des virus, bact\u00e9ries, etc., minimisant ainsi les infections respiratoires. En dehors de ces plages, l\u2019environnement peut \u00eatre consid\u00e9r\u00e9 comme non optimal pour la sant\u00e9.<\/span><\/p>\n<h2><b>Solutions Borealis pour les \u00e9tablissements scolaires<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Le document pr\u00e9sente diff\u00e9rentes solutions pour assurer une ventilation correcte dans ces \u00e9tablissements et recommande des technologies d\u00e9velopp\u00e9es par Borealis :<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Purification de l&rsquo;air par lumi\u00e8re ultraviolette, avec des solutions portables ou int\u00e9gr\u00e9es dans les conduits d&rsquo;air.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">Cette recommandation appuie notre gamme <\/span><a href=\"https:\/\/borealisclima.com\/fr\/systemes-ultraviolets\/\"><span style=\"font-weight: 400;\">Borealis UV<\/span><\/a><span style=\"font-weight: 400;\"> d\u2019\u00e9quipements germicides \u00e0 lumi\u00e8re ultraviolette (UV-C), sans production d\u2019ozone.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ventilation m\u00e9canique : ajout d\u2019\u00e9quipements de ventilation m\u00e9canique aux b\u00e2timents anciens ne disposant pas de cette option. La solution \u00ab<\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1Rid3aNZQLxWt4hr_mUtgQEP-4erUpIPh\/view?usp=drive_link\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Miniven<\/span><\/a><span style=\"font-weight: 400;\">\u00bb constitue une alternative \u00e9conomique et flexible dans ces cas.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AFEC, l\u2019Association des Fabricants d\u2019\u00c9quipements de Climatisation, a publi\u00e9 le guide des \u00ab\u00a0Recommandations de Ventilation pour les \u00c9tablissements Scolaires\u00a0\u00bb, auquel Borealis a collabor\u00e9 en tant que membre du groupe de travail charg\u00e9 de son \u00e9laboration. Ce guide propose diff\u00e9rentes recommandations, destin\u00e9es aux dirigeants d\u2019\u00e9tablissements, aux enseignants, aux associations de parents, aux administrations publiques, ainsi qu\u2019aux&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[206],"tags":[],"class_list":["post-1952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-secteurs","category-206","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs.\" \/>\n<meta property=\"og:description\" content=\"AFEC, l\u2019Association des Fabricants d\u2019\u00c9quipements de Climatisation, a publi\u00e9 le guide des \u00ab\u00a0Recommandations de Ventilation pour les \u00c9tablissements Scolaires\u00a0\u00bb, auquel Borealis a collabor\u00e9 en tant que membre du groupe de travail charg\u00e9 de son \u00e9laboration. Ce guide propose diff\u00e9rentes recommandations, destin\u00e9es aux dirigeants d\u2019\u00e9tablissements, aux enseignants, aux associations de parents, aux administrations publiques, ainsi qu\u2019aux&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/\" \/>\n<meta property=\"og:site_name\" content=\"Borealis | Energie thermique\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T05:56:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T10:53:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2021\/06\/ventilacion-centros-educativos-14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2167\" \/>\n\t<meta property=\"og:image:height\" content=\"1133\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Borealis Energ\u00eda T\u00e9rmica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Borealis Energ\u00eda T\u00e9rmica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/\"},\"author\":{\"name\":\"Borealis Energ\u00eda T\u00e9rmica\",\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/#\\\/schema\\\/person\\\/662ff62fb5106b739855abb27b6e6af0\"},\"headline\":\"L&rsquo;AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs.\",\"datePublished\":\"2021-06-15T05:56:58+00:00\",\"dateModified\":\"2025-06-26T10:53:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/\"},\"wordCount\":698,\"image\":{\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/ventilacion-centros-educativos-14.jpg\",\"articleSection\":[\"Secteurs\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/\",\"url\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/\",\"name\":\"L'AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/ventilacion-centros-educativos-14.jpg\",\"datePublished\":\"2021-06-15T05:56:58+00:00\",\"dateModified\":\"2025-06-26T10:53:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/#\\\/schema\\\/person\\\/662ff62fb5106b739855abb27b6e6af0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/ventilacion-centros-educativos-14.jpg\",\"contentUrl\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/ventilacion-centros-educativos-14.jpg\",\"width\":2167,\"height\":1133,\"caption\":\"ventilacion-centros-educativos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/\",\"name\":\"Borealis | Energie thermique\",\"description\":\"Entreprise du groupe Campos Corporaci\u00f3na\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/#\\\/schema\\\/person\\\/662ff62fb5106b739855abb27b6e6af0\",\"name\":\"Borealis Energ\u00eda T\u00e9rmica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g\",\"caption\":\"Borealis Energ\u00eda T\u00e9rmica\"},\"url\":\"https:\\\/\\\/borealisclima.com\\\/fr\\\/author\\\/borealis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/","og_locale":"fr_FR","og_type":"article","og_title":"L'AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs.","og_description":"AFEC, l\u2019Association des Fabricants d\u2019\u00c9quipements de Climatisation, a publi\u00e9 le guide des \u00ab\u00a0Recommandations de Ventilation pour les \u00c9tablissements Scolaires\u00a0\u00bb, auquel Borealis a collabor\u00e9 en tant que membre du groupe de travail charg\u00e9 de son \u00e9laboration. Ce guide propose diff\u00e9rentes recommandations, destin\u00e9es aux dirigeants d\u2019\u00e9tablissements, aux enseignants, aux associations de parents, aux administrations publiques, ainsi qu\u2019aux&hellip;","og_url":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/","og_site_name":"Borealis | Energie thermique","article_published_time":"2021-06-15T05:56:58+00:00","article_modified_time":"2025-06-26T10:53:30+00:00","og_image":[{"width":2167,"height":1133,"url":"https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2021\/06\/ventilacion-centros-educativos-14.jpg","type":"image\/jpeg"}],"author":"Borealis Energ\u00eda T\u00e9rmica","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Borealis Energ\u00eda T\u00e9rmica","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/#article","isPartOf":{"@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/"},"author":{"name":"Borealis Energ\u00eda T\u00e9rmica","@id":"https:\/\/borealisclima.com\/fr\/#\/schema\/person\/662ff62fb5106b739855abb27b6e6af0"},"headline":"L&rsquo;AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs.","datePublished":"2021-06-15T05:56:58+00:00","dateModified":"2025-06-26T10:53:30+00:00","mainEntityOfPage":{"@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/"},"wordCount":698,"image":{"@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/#primaryimage"},"thumbnailUrl":"https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2021\/06\/ventilacion-centros-educativos-14.jpg","articleSection":["Secteurs"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/","url":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/","name":"L'AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs.","isPartOf":{"@id":"https:\/\/borealisclima.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/#primaryimage"},"image":{"@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/#primaryimage"},"thumbnailUrl":"https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2021\/06\/ventilacion-centros-educativos-14.jpg","datePublished":"2021-06-15T05:56:58+00:00","dateModified":"2025-06-26T10:53:30+00:00","author":{"@id":"https:\/\/borealisclima.com\/fr\/#\/schema\/person\/662ff62fb5106b739855abb27b6e6af0"},"breadcrumb":{"@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/#primaryimage","url":"https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2021\/06\/ventilacion-centros-educativos-14.jpg","contentUrl":"https:\/\/borealisclima.com\/fr\/wp-content\/uploads\/sites\/4\/2021\/06\/ventilacion-centros-educativos-14.jpg","width":2167,"height":1133,"caption":"ventilacion-centros-educativos"},{"@type":"BreadcrumbList","@id":"https:\/\/borealisclima.com\/fr\/afec-publie-un-guide-de-recommandations-de-ventilation-pour-les-centres-educatifs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/borealisclima.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;AFEC publie un guide de recommandations en mati\u00e8re de ventilation pour les centres \u00e9ducatifs."}]},{"@type":"WebSite","@id":"https:\/\/borealisclima.com\/fr\/#website","url":"https:\/\/borealisclima.com\/fr\/","name":"Borealis | Energie thermique","description":"Entreprise du groupe Campos Corporaci\u00f3na","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/borealisclima.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/borealisclima.com\/fr\/#\/schema\/person\/662ff62fb5106b739855abb27b6e6af0","name":"Borealis Energ\u00eda T\u00e9rmica","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g","caption":"Borealis Energ\u00eda T\u00e9rmica"},"url":"https:\/\/borealisclima.com\/fr\/author\/borealis\/"}]}},"_links":{"self":[{"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/posts\/1952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/comments?post=1952"}],"version-history":[{"count":0,"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/posts\/1952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/media\/1960"}],"wp:attachment":[{"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/media?parent=1952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/categories?post=1952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borealisclima.com\/fr\/wp-json\/wp\/v2\/tags?post=1952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}